{"id":2083,"date":"2025-11-05T08:00:43","date_gmt":"2025-11-04T23:00:43","guid":{"rendered":"https:\/\/classico.co.jp\/?page_id=2083"},"modified":"2025-11-06T18:18:16","modified_gmt":"2025-11-06T09:18:16","slug":"presentations","status":"publish","type":"page","link":"https:\/\/classico.co.jp\/en\/ir\/presentations\/","title":{"rendered":"Business Results Presentation Materials"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":261386604,"featured_media":0,"parent":2005,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-ir-presentations.php","meta":{"_acf_changed":false,"advanced_seo_description":"The following is a list of Classico Inc's financial results.","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"_wpcom_ai_launchpad_contact_page":false,"_wpcom_ai_launchpad_events_page":false,"_wpcom_ai_launchpad_video_page":false,"_wpcom_ai_launchpad_portfolio_piece":false,"footnotes":""},"class_list":["post-2083","page","type-page","status-publish","hentry"],"acf":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PginP1-xB","_links":{"self":[{"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/pages\/2083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/users\/261386604"}],"replies":[{"embeddable":true,"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/comments?post=2083"}],"version-history":[{"count":1,"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/pages\/2083\/revisions"}],"predecessor-version":[{"id":2120,"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/pages\/2083\/revisions\/2120"}],"up":[{"embeddable":true,"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/pages\/2005"}],"wp:attachment":[{"href":"https:\/\/classico.co.jp\/en\/wp-json\/wp\/v2\/media?parent=2083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}